{"id":152,"count":491,"description":"","link":"https:\/\/w1.aua.gr\/poa\/unity\/undergraduate\/","name":"\u03a0\u03c1\u03bf\u03c0\u03c4\u03c5\u03c7\u03b9\u03b1\u03ba\u03ac","slug":"undergraduate","taxonomy":"unity","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/w1.aua.gr\/poa\/wp-json\/wp\/v2\/unity\/152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/w1.aua.gr\/poa\/wp-json\/wp\/v2\/unity"}],"about":[{"href":"https:\/\/w1.aua.gr\/poa\/wp-json\/wp\/v2\/taxonomies\/unity"}],"wp:post_type":[{"href":"https:\/\/w1.aua.gr\/poa\/wp-json\/wp\/v2\/announcements-poa?unity=152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}