{"id":28,"count":56,"description":"","link":"https:\/\/w1.aua.gr\/kedivim\/semester\/complete\/","name":"\u039f\u03bb\u03bf\u03ba\u03bb\u03b7\u03c1\u03c9\u03bc\u03ad\u03bd\u03bf","slug":"complete","taxonomy":"semester","parent":0,"meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/w1.aua.gr\/kedivim\/wp-json\/wp\/v2\/semester\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/w1.aua.gr\/kedivim\/wp-json\/wp\/v2\/semester"}],"about":[{"href":"https:\/\/w1.aua.gr\/kedivim\/wp-json\/wp\/v2\/taxonomies\/semester"}],"wp:post_type":[{"href":"https:\/\/w1.aua.gr\/kedivim\/wp-json\/wp\/v2\/courses?semester=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}